{"id":76926,"date":"2017-12-04T10:34:24","date_gmt":"2017-12-04T09:34:24","guid":{"rendered":"https:\/\/www.ilcam.com\/?p=76926"},"modified":"2018-02-12T19:33:56","modified_gmt":"2018-02-12T18:33:56","slug":"centro-logistico","status":"publish","type":"post","link":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/","title":{"rendered":"CENTRO LOGISTICO"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text]Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.<\/p>\n<ul>\n<li>30.000 metri quadrati di magazzini coperti<\/li>\n<li>Due magazzini:<\/li>\n<\/ul>\n<p>W1:<\/p>\n<ul>\n<li>Magazzino AS \/ RS (sistema automatico di stoccaggio e recupero)<\/li>\n<li>rifornito con AGV dalla struttura Licar 2<\/li>\n<li>principale utilizzo per stoccaggio produzione propria di Licar<\/li>\n<li>Capacit\u00e0 di stoccaggio di 13.000 pallet *<\/li>\n<\/ul>\n<p>W2:<\/p>\n<ul>\n<li>Sistema di stoccaggio e recupero uomo a bordo e magazzino di scaffalature compattabili<\/li>\n<li>30% dello spazio con scaffalature compattabili dedicate agli accessori azionati con carrelli retrattili<\/li>\n<li>30% dello spazio con scaffalature compattabili dedicate ai pallet standard azionati con carrelli retrattili<\/li>\n<li>40% dello spazio dedicato agli impilatori di scaffali alti<\/li>\n<li>Capacit\u00e0 di stoccaggio di 16.000 pallet *<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_column_text]*: 800&#215;1200 dimensione pallet[\/vc_column_text][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_single_image image=&#8221;76923&#8243;][vc_empty_space][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<ul>\n<li>Operativo dalle 07:00 alle 20:00<\/li>\n<li>Due baie di carico dedicate ai container (caricamento posteriore)<\/li>\n<li>Capacit\u00e0 di carico di 15 camion al giorno (caricamento laterale)<\/li>\n<li>Tutto il materiale del gruppo ILCAM stoccato in un unico posto<\/li>\n<li>Pi\u00f9 facilit\u00e0 nell\u2019organizzare camion completi<\/li>\n<li>Possibilit\u00e0 di combinare sullo stesso camion materiale prodotto da diverse unit\u00e0 del Gruppo (ILCAM, Licar, Lanta)<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.<\/p>\n","protected":false},"author":4,"featured_media":76922,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[34],"tags":[76],"class_list":["post-76926","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ilcam-voice-it","tag-logistic-hub-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CENTRO LOGISTICO - ILCAM<\/title>\n<meta name=\"description\" content=\"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CENTRO LOGISTICO - ILCAM\" \/>\n<meta property=\"og:description\" content=\"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/\" \/>\n<meta property=\"og:site_name\" content=\"ILCAM\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-04T09:34:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-02-12T18:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"815\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Malisan\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Malisan\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/\"},\"author\":{\"name\":\"Andrea Malisan\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#\\\/schema\\\/person\\\/29ffe81a0cd13c6ebffc2c1dfaffccac\"},\"headline\":\"CENTRO LOGISTICO\",\"datePublished\":\"2017-12-04T09:34:24+00:00\",\"dateModified\":\"2018-02-12T18:33:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/\"},\"wordCount\":234,\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/main-Lager-Logistik.jpg\",\"keywords\":[\"Logistic Hub\"],\"articleSection\":[\"ILCAM voice\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/\",\"url\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/\",\"name\":\"CENTRO LOGISTICO - ILCAM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/main-Lager-Logistik.jpg\",\"datePublished\":\"2017-12-04T09:34:24+00:00\",\"dateModified\":\"2018-02-12T18:33:56+00:00\",\"description\":\"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/main-Lager-Logistik.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/main-Lager-Logistik.jpg\",\"width\":1400,\"height\":815},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/ilcam-voice-it\\\/centro-logistico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CENTRO LOGISTICO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/\",\"name\":\"ILCAM\",\"description\":\"Masters of furniture apparel\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#organization\",\"name\":\"ILCAM\",\"url\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-ilcam_new.png\",\"contentUrl\":\"https:\\\/\\\/www.ilcam.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/logo-ilcam_new.png\",\"width\":756,\"height\":322,\"caption\":\"ILCAM\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ilcam.com\\\/it\\\/#\\\/schema\\\/person\\\/29ffe81a0cd13c6ebffc2c1dfaffccac\",\"name\":\"Andrea Malisan\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CENTRO LOGISTICO - ILCAM","description":"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/","og_locale":"it_IT","og_type":"article","og_title":"CENTRO LOGISTICO - ILCAM","og_description":"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.","og_url":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/","og_site_name":"ILCAM","article_published_time":"2017-12-04T09:34:24+00:00","article_modified_time":"2018-02-12T18:33:56+00:00","og_image":[{"width":1400,"height":815,"url":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg","type":"image\/jpeg"}],"author":"Andrea Malisan","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Malisan","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#article","isPartOf":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/"},"author":{"name":"Andrea Malisan","@id":"https:\/\/www.ilcam.com\/it\/#\/schema\/person\/29ffe81a0cd13c6ebffc2c1dfaffccac"},"headline":"CENTRO LOGISTICO","datePublished":"2017-12-04T09:34:24+00:00","dateModified":"2018-02-12T18:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/"},"wordCount":234,"publisher":{"@id":"https:\/\/www.ilcam.com\/it\/#organization"},"image":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg","keywords":["Logistic Hub"],"articleSection":["ILCAM voice"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/","url":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/","name":"CENTRO LOGISTICO - ILCAM","isPartOf":{"@id":"https:\/\/www.ilcam.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#primaryimage"},"image":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg","datePublished":"2017-12-04T09:34:24+00:00","dateModified":"2018-02-12T18:33:56+00:00","description":"Packaging design, etichettatura, logistica di magazzino e di trasporto, in ILCAM sono personalizzate ad hoc per il cliente, al fine di venire incontro alle esigenze pi\u00f9 particolari e fornire il pi\u00f9 alto livello di servizio.","breadcrumb":{"@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#primaryimage","url":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg","contentUrl":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2017\/12\/main-Lager-Logistik.jpg","width":1400,"height":815},{"@type":"BreadcrumbList","@id":"https:\/\/www.ilcam.com\/it\/ilcam-voice-it\/centro-logistico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.ilcam.com\/it\/"},{"@type":"ListItem","position":2,"name":"CENTRO LOGISTICO"}]},{"@type":"WebSite","@id":"https:\/\/www.ilcam.com\/it\/#website","url":"https:\/\/www.ilcam.com\/it\/","name":"ILCAM","description":"Masters of furniture apparel","publisher":{"@id":"https:\/\/www.ilcam.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ilcam.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.ilcam.com\/it\/#organization","name":"ILCAM","url":"https:\/\/www.ilcam.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ilcam.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2022\/01\/logo-ilcam_new.png","contentUrl":"https:\/\/www.ilcam.com\/wp-content\/uploads\/2022\/01\/logo-ilcam_new.png","width":756,"height":322,"caption":"ILCAM"},"image":{"@id":"https:\/\/www.ilcam.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.ilcam.com\/it\/#\/schema\/person\/29ffe81a0cd13c6ebffc2c1dfaffccac","name":"Andrea Malisan"}]}},"_links":{"self":[{"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/posts\/76926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/comments?post=76926"}],"version-history":[{"count":3,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/posts\/76926\/revisions"}],"predecessor-version":[{"id":76930,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/posts\/76926\/revisions\/76930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/media\/76922"}],"wp:attachment":[{"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/media?parent=76926"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/categories?post=76926"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ilcam.com\/it\/wp-json\/wp\/v2\/tags?post=76926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}